{"id":40489,"date":"2020-01-13T12:22:56","date_gmt":"2020-01-13T12:22:56","guid":{"rendered":"https:\/\/wp.lvh.me\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/"},"modified":"2023-12-01T00:40:45","modified_gmt":"2023-12-01T00:40:45","slug":"desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3","status":"publish","type":"post","link":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/","title":{"rendered":"Desactivar la confirmacion de remitentes en Mailrelay v3"},"content":{"rendered":"<p>Quiz\u00e1 debamos empezar por explicar cual puede ser el motivo para desactivar la confirmaci\u00f3n de remitentes.<\/p>\n<p>Este sistema est\u00e1 implementado para garantizar la seguridad del sistema y evitar que pueda haber env\u00edos con remitentes mal configurados o desde dominios que no est\u00e1n autorizados por sus leg\u00edtimos due\u00f1os.<\/p>\n<p>Por tanto, \u00bfcual puede ser el motivo para desactivarlo?<\/p>\n<p>Pues b\u00e1sicamente es algo que pueden solicitar clientes como agencias publicitarias o gabinetes de prensa que mandan con varios distintos de sus clientes y necesitan cierta agilidad a la hora de los env\u00edos.<\/p>\n<p>Otra posibilidad son grandes compa\u00f1\u00edas que mandan boletines desde nuevos correo a menudo por ejemplo para presentaci\u00f3n de nuevos empleados, proyectos, etc.<\/p>\n<p>En estos casos puede ser complejo que les autoricen de forma inmediata los nuevos remitentes con los enlaces de confirmaci\u00f3n y si hay que cumplir horarios y agenda de env\u00edos esto puede ser un inconveniente.<\/p>\n<p>La soluci\u00f3n, hasta ahora en la V2, era desactivar la comprobaci\u00f3n y delegar en la agencia cliente de Mailrelay la responsabilidad de asegurarse que tienen el permiso para enviar con los remitentes de cualquier dominio B2B.<\/p>\n<p>Pero esto planteaba un problema de seguridad ya que hab\u00eda que fiarse de la palabra del cliente respecto a tener el permiso para usar los dominios de terceros e incluso cumpli\u00e9ndolo, si tuviera un acceso no autorizado a su panel, se podr\u00edan hacer env\u00edos desde cualquier remitente o dominio sin autorizaci\u00f3n de su leg\u00edtimo propietario.<\/p>\n<h2>\u00b7&nbsp;En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.<\/h2>\n<p>Desde el panel se pueden configurar nuevos remitentes sin necesidad de verificarlos con la URL del mail de confirmaci\u00f3n, pero para que el sistema los admita, en el dominio remitente ser\u00e1 necesario a\u00f1adir un c\u00f3digo de autentificaci\u00f3n como un registro TXT en el DNS.<\/p>\n<p>Esto garantiza que el propietario estar\u00e1 al tanto y habr\u00e1 dado el permiso ya que es imposible que nadie modifique esto salvo el registrador del domino en su panel de control.<\/p>\n<p>Para activarlo el el panel de Mailrelay V3 hay que ir a <strong>Boletines<\/strong> \/ <strong>Remitentes<\/strong> y pulsar en el bot\u00f3n de la derecha para acceder a \u201cConfirmaci\u00f3n de dominios\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25837\" title=\"confirmaci\u00f3n de dominios\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios.jpg\" alt=\"confirmaci\u00f3n de dominios\" width=\"499\" height=\"360\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios.jpg 534w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-300x216.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-110x79.jpg 110w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<p>Una vez dentro de esa pantalla, hacemos click en <strong>a\u00f1adir<\/strong> y accedemos a la pantalla que nos informa de que entrada debemos configurar en el DNS:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25838\" title=\"Confirmaci\u00f3n de dominios\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-2.jpg\" alt=\"Confirmaci\u00f3n de dominios\" width=\"630\" height=\"612\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-2.jpg 695w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-2-300x291.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-2-110x107.jpg 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>En concreto es un registro TXT en un subdominio que debemos crear.<\/p>\n<p><strong>En la captura anterior, la parte subrayada en azul indica el subdomino y la parte en verde el contenido que debe tener el registro TXT.<\/strong><\/p>\n<p>As\u00ed se a\u00f1adir\u00eda por ejemplo en el editor de zona DNS de Cpanel, seleccionando configurar dominio y \u201cA\u00f1adir Registro\u201d eligiendo tipo TXT:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25839\" title=\"Confirmaci\u00f3n de dominios\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3.jpg\" alt=\"Confirmaci\u00f3n de dominios\" width=\"630\" height=\"185\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3.jpg 1178w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3-300x88.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3-1024x301.jpg 1024w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3-768x226.jpg 768w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-3-110x32.jpg 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>Una vez configurado podemos ir al panel de Mailrelay y darle a Confirmar Dominio <em>(en algunos paneles DNS puede que no sea inmediata la creaci\u00f3n y tarde un tiempo en estar listo)<\/em>.<\/p>\n<p><strong>Si todo est\u00e1 ok veremos este informe y ya podremos usar cualquier email de ese dominio como remitente sin necesidad de confirmarlo:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25840\" title=\"Confirmaci\u00f3n de dominios\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-4.jpg\" alt=\"Confirmaci\u00f3n de dominios\" width=\"630\" height=\"226\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-4.jpg 733w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-4-300x108.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/confirmacion-de-dominios-4-110x39.jpg 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>Comentar para finalizar que dada registro TXT y subdominio donde a\u00f1adirlo son \u00fanicos para cada cuenta de Mailrelay, por tanto solo se podr\u00e1n a\u00f1adir remitentes sin confirmar de dicho dominio en el panel de la cuenta que los haya generado.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/noesoriano?originalSubdomain=es\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14165 size-full\" title=\"No\u00e9 Soriano\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/01\/noe-soriano.jpg\" alt=\"No\u00e9 Soriano\" width=\"630\" height=\"250\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/01\/noe-soriano.jpg 630w, https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/01\/noe-soriano-300x119.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/01\/noe-soriano-110x44.jpg 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1 debamos empezar por explicar cual puede ser el motivo para desactivar la confirmaci\u00f3n de remitentes. Este sistema est\u00e1 implementado para garantizar la seguridad del sistema y evitar que pueda haber env\u00edos con remitentes mal configurados o desde dominios que no est\u00e1n autorizados por sus leg\u00edtimos due\u00f1os. Por tanto, \u00bfcual puede ser el motivo para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[231,16],"tags":[],"class_list":["post-40489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-email-marketing","category-uncategorized-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay<\/title>\n<meta name=\"description\" content=\"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay\" \/>\n<meta property=\"og:description\" content=\"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailrelay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mailrelay\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-13T12:22:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-01T00:40:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"No\u00e9 Soriano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:site\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9 Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/\"},\"author\":{\"name\":\"No\u00e9 Soriano\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#\\\/schema\\\/person\\\/015806c54f5ded021ad304cd2e1b8c1d\"},\"headline\":\"Desactivar la confirmacion de remitentes en Mailrelay v3\",\"datePublished\":\"2020-01-13T12:22:56+00:00\",\"dateModified\":\"2023-12-01T00:40:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/\"},\"wordCount\":575,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png\",\"articleSection\":[\"email marketing\",\"Uncategorized @pt\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/\",\"name\":\"\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png\",\"datePublished\":\"2020-01-13T12:22:56+00:00\",\"dateModified\":\"2023-12-01T00:40:45+00:00\",\"description\":\"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png\",\"width\":630,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/2020\\\/01\\\/13\\\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desactivar la confirmacion de remitentes en Mailrelay v3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/\",\"name\":\"Mailrelay\",\"description\":\"Mailrelay.com - Email Marketing Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#organization\",\"name\":\"Mailrelay\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"width\":613,\"height\":291,\"caption\":\"Mailrelay\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mailrelay\\\/\",\"https:\\\/\\\/x.com\\\/mailrelay\",\"https:\\\/\\\/www.youtube.com\\\/mailrelay-email-marketing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/#\\\/schema\\\/person\\\/015806c54f5ded021ad304cd2e1b8c1d\",\"name\":\"No\u00e9 Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g\",\"caption\":\"No\u00e9 Soriano\"},\"sameAs\":[\"http:\\\/\\\/mailrelay.com\"],\"url\":\"https:\\\/\\\/mailrelay.com\\\/es\\\/blog\\\/author\\\/noe-soriano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay","description":"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/","og_locale":"es_ES","og_type":"article","og_title":"\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay","og_description":"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.","og_url":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/","og_site_name":"Mailrelay","article_publisher":"https:\/\/www.facebook.com\/Mailrelay\/","article_published_time":"2020-01-13T12:22:56+00:00","article_modified_time":"2023-12-01T00:40:45+00:00","og_image":[{"width":630,"height":340,"url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png","type":"image\/png"}],"author":"No\u00e9 Soriano","twitter_card":"summary_large_image","twitter_creator":"@mailrelay","twitter_site":"@mailrelay","twitter_misc":{"Escrito por":"No\u00e9 Soriano","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#article","isPartOf":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/"},"author":{"name":"No\u00e9 Soriano","@id":"https:\/\/mailrelay.com\/es\/#\/schema\/person\/015806c54f5ded021ad304cd2e1b8c1d"},"headline":"Desactivar la confirmacion de remitentes en Mailrelay v3","datePublished":"2020-01-13T12:22:56+00:00","dateModified":"2023-12-01T00:40:45+00:00","mainEntityOfPage":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/"},"wordCount":575,"commentCount":0,"publisher":{"@id":"https:\/\/mailrelay.com\/es\/#organization"},"image":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png","articleSection":["email marketing","Uncategorized @pt"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/","url":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/","name":"\u25ba Desactivar la Confirmacion de Remitentes en Mailrelay","isPartOf":{"@id":"https:\/\/mailrelay.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#primaryimage"},"image":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png","datePublished":"2020-01-13T12:22:56+00:00","dateModified":"2023-12-01T00:40:45+00:00","description":"En la versi\u00f3n 3 de Mailrelay hemos dado soluci\u00f3n a este problema.","breadcrumb":{"@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#primaryimage","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png","width":630,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/mailrelay.com\/es\/blog\/2020\/01\/13\/desactivar-la-confirmacion-de-remitentes-en-mailrelay-v3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mailrelay.com\/es\/"},{"@type":"ListItem","position":2,"name":"Desactivar la confirmacion de remitentes en Mailrelay v3"}]},{"@type":"WebSite","@id":"https:\/\/mailrelay.com\/es\/#website","url":"https:\/\/mailrelay.com\/es\/","name":"Mailrelay","description":"Mailrelay.com - Email Marketing Software","publisher":{"@id":"https:\/\/mailrelay.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mailrelay.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mailrelay.com\/es\/#organization","name":"Mailrelay","url":"https:\/\/mailrelay.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mailrelay.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","width":613,"height":291,"caption":"Mailrelay"},"image":{"@id":"https:\/\/mailrelay.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mailrelay\/","https:\/\/x.com\/mailrelay","https:\/\/www.youtube.com\/mailrelay-email-marketing"]},{"@type":"Person","@id":"https:\/\/mailrelay.com\/es\/#\/schema\/person\/015806c54f5ded021ad304cd2e1b8c1d","name":"No\u00e9 Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f16046acc14e3a26903ab4e9b4ba51e9b4b7b0c22b4f9f65f61bbfb98aed442?s=96&d=mm&r=g","caption":"No\u00e9 Soriano"},"sameAs":["http:\/\/mailrelay.com"],"url":"https:\/\/mailrelay.com\/es\/blog\/author\/noe-soriano\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",630,340,false],"thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3-150x150.png",150,150,true],"medium":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3-300x162.png",300,162,true],"medium_large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",630,340,false],"large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",630,340,false],"1536x1536":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",630,340,false],"2048x2048":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",630,340,false],"testimonials":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3-110x59.png",110,59,true],"author-image":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",60,32,false],"yarpp-thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/01\/Desactivar-la-confirmacion-de-remitentes-en-Mailrelay-v3.png",120,65,false]},"uagb_author_info":{"display_name":"No\u00e9 Soriano","author_link":"https:\/\/mailrelay.com\/es\/blog\/author\/noe-soriano\/"},"uagb_comment_info":0,"uagb_excerpt":"Quiz\u00e1 debamos empezar por explicar cual puede ser el motivo para desactivar la confirmaci\u00f3n de remitentes. Este sistema est\u00e1 implementado para garantizar la seguridad del sistema y evitar que pueda haber env\u00edos con remitentes mal configurados o desde dominios que no est\u00e1n autorizados por sus leg\u00edtimos due\u00f1os. Por tanto, \u00bfcual puede ser el motivo para&hellip;","_links":{"self":[{"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/posts\/40489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/comments?post=40489"}],"version-history":[{"count":4,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/posts\/40489\/revisions"}],"predecessor-version":[{"id":73183,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/posts\/40489\/revisions\/73183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/media\/25843"}],"wp:attachment":[{"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/media?parent=40489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/categories?post=40489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mailrelay.com\/es\/wp-json\/wp\/v2\/tags?post=40489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}