{"id":41710,"date":"2015-05-12T05:42:42","date_gmt":"2015-05-12T05:42:42","guid":{"rendered":"https:\/\/wp.lvh.me\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/"},"modified":"2023-09-12T12:11:52","modified_gmt":"2023-09-12T12:11:52","slug":"9-mitos-sobre-taxa-de-entrega-de-mala-direta","status":"publish","type":"post","link":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/","title":{"rendered":"9 mitos sobre taxa de entrega de mala direta"},"content":{"rendered":"<p>A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.<\/p>\n<p>Cada pequeno detalhe pode afetar o resultado final.<\/p>\n<p>Temos que estar muito conscientes sobre eles! E revisar todos os pontos rigorosamente.<\/p>\n<p>A verdade \u00e9 que \u00e9 uma tarefa dif\u00edcil, uma vez que os ISP n\u00e3o enviam muitas informa\u00e7\u00f5es (normal, caso contr\u00e1rio, spammers poderiam se adaptar facilmente).<\/p>\n<p>Precisamos olhar para todos os sinais, como as taxas de abertura, n\u00famero de opt-outs, de queixas de spam, por exemplo, tentando detectar padr\u00f5es, efetuar testes e altera\u00e7\u00f5es sempre que necess\u00e1rio, para ver o que acontece.<\/p>\n<p>A taxa de entrega n\u00e3o pode ser medida sem um contexto. Existem muitos fatores que devem ser revisados.<\/p>\n<p>Dependendo da reputa\u00e7\u00e3o do remetente\u00a0 um percentual da mala direta pode ser rejeitada, ent\u00e3o h\u00e1 mais par\u00e2metros a ter em conta.<\/p>\n<p>Lembro-me de um artigo h\u00e1 algum tempo atr\u00e1s, a saber:<\/p>\n<p>Sua campanha enviada para o Hotmail, Gmail e o Yahoo est\u00e1 chegando como spam?<\/p>\n<p>Onde voc\u00ea pode ver uma tabela interessante.\u00a0 Com uma baixa reputa\u00e7\u00e3o, at\u00e9 83,5% dos emails podem ser rejeitados. N\u00e3o estamos falando sobre a pasta de spam, mas sobre emails que nem se quer s\u00e3o aceitos pelos servidores destino. Mas mesmo com uma boa reputa\u00e7\u00e3o, podem ocorrer problemas de emails n\u00e3o aceitos. De qualquer forma, eu coletei alguns erros que muitos usu\u00e1rios cometem.<\/p>\n<p>Frequentemente, al\u00e9m de mitos, para que voc\u00ea saiba o que pode ser feito para melhorar a taxa de entrega da sua mala direta.<\/p>\n<h3>Mitos sobre a taxa de entrega em mala direta<\/h3>\n<p>Vamos come\u00e7ar a ver esta pequena lista:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8536\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/mail.png\" alt=\"mail\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\">\n<p><strong>1) Se o teste chegou corretamente, todos os emails enviados chegar\u00e3o<\/strong><\/p>\n<\/div>\n<p><em><strong>Falso.<\/strong><\/em> Ao enviar uma mala direta para muitos usu\u00e1rios, mesmo que o teste tenha sido recebido corretamente, pode ocorrer de alguns assinantes receb\u00ea-la como SPAM. O oposto tamb\u00e9m \u00e9 verdadeiro, embora um teste tenha chegado no spam, isto n\u00e3o significa que todos os emails chegar\u00e3o como spam. Como explicado anteriormente, n\u00e3o \u00e9 uma regra fixa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32852\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/carpeta.png\" alt=\"carpeta\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\"><strong>Se o email est\u00e1 chegando na aba promo\u00e7\u00f5es, \u00e9 porque algo est\u00e1 errado<\/strong><\/div>\n<p><em><strong>Falso.<\/strong><\/em>Normalmente, as campanhas de email marketing tem conte\u00fado promocional, ent\u00e3o s\u00e3o colocadas na pasta promo\u00e7\u00f5es. N\u00e3o que haja algo de errado, a pasta promo\u00e7\u00f5es existe exatamente para isto. Se um determinado assinante mover sua mala direta para a pasta principal, \u00e9 uma decis\u00e3o pessoal deste assinante, e n\u00e3o ser\u00e1 aplicada a outros usu\u00e1rios da lista.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32800\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/lista.png\" alt=\"lista\" width=\"100\" height=\"80\" \/><\/p>\n<p><strong>3) N\u00e3o importa que o mailing list tenha emails incorretos ou inexistentes. O servidor destino apenas ir\u00e1 ignorar estes emails, sem afetar o restante<\/strong><\/p>\n<p style=\"margin-left: 280px;\"><em><strong>Falso.<\/strong><\/em> Se um ISP detectar que voc\u00ea est\u00e1 tentando enviar muitos emails incorretos ou inexistentes, o dom\u00ednio ser\u00e1 penalizado. E no caso de voc\u00ea ser um spammer, muitos dos emails existentes n\u00e3o ir\u00e3o receber sua mala direta na caixa de entrada. \u00c9 o pre\u00e7o a pagar por n\u00e3o fazer as coisas direito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32802\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/thumbup.png\" alt=\"thumbup\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\">\n<p><strong>4) Como eu nunca enviei uma mala direta, minha reputa\u00e7\u00e3o \u00e9 boa<\/strong><\/p>\n<\/div>\n<p><em><strong>Falso.<\/strong><\/em> Se um dom\u00ednio nunca enviou uma campanha, n\u00e3o ter\u00e1 uma boa reputa\u00e7\u00e3o, inicialmente ser\u00e1 uma reputa\u00e7\u00e3o neutra. Nas primeiras campanhas, alguns filtros podem colocar alguns emails em &#8220;n\u00e3o desejado&#8221; para ver como os assinantes interagem com as newsletters. Se os assinantes marcarem o email como email desejado, isto ser\u00e1 positivo para a reputa\u00e7\u00e3o do remetente. Caso contr\u00e1rio, a reputa\u00e7\u00e3o pode ser prejudicada. Mas a boa reputa\u00e7\u00e3o, como em todos os aspectos da vida, precisa ser conquistada. Eu nunca perdi uma luta de kick boxing. Mas isto n\u00e3o significa que tenha uma boa reputa\u00e7\u00e3o neste esporte, nem boa nem m\u00e1 at\u00e9 que eu tente participar de uma luta, pela primeira vez (e se descubra o qu\u00e3o ruim eu seja neste esporte). \u00c9 um exemplo absurdo, mas creio que fica f\u00e1cil entender.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8536\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/mail.png\" alt=\"mail\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\">\n<p><strong>5) O uso excessivo de imagens, ou criar um email com uma \u00fanica imagem n\u00e3o faz a m\u00ednima diferen\u00e7a, pois afinal \u00e9 apenas um email.<\/strong><\/p>\n<\/div>\n<p><em><strong>Falso. <\/strong><\/em>Claro que o conte\u00fado ir\u00e1 influenciar, n\u00e3o devemos negligenciar esta parte, enviar apenas uma imagem sem conte\u00fado de texto, ou muito pouco texto com apenas um link, pode apresentar problemas, embora muitos usu\u00e1rios n\u00e3o prestem aten\u00e7\u00e3o nisso, s\u00e3o detalhes muito importantes. Lembre-se que os spammers n\u00e3o s\u00e3o caracterizados por bons emails ou pelo conte\u00fado enviado. Se o que voc\u00ea envia parece Spam &#8230;\u00a0 Em suma a sua mala direta n\u00e3o tem que apenas ser boa, precisa parecer boa. Felizmente, com a Mailrelay voc\u00ea tem um bot\u00e3o para verifica\u00e7\u00e3o do spam score da sua mala direta, com o qual voc\u00ea pode rever a sua campanha antes de envi\u00e1-la.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32804\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/edicion.png\" alt=\"edicion\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\">\n<p><strong>6) Incluir um link de cancelamento \u00e9 opcional e n\u00e3o afeta a taxa de entrega<\/strong><\/p>\n<\/div>\n<p><em><strong>Falso.<\/strong><\/em> N\u00e3o incluir um link de cancelamento pode afetar de formas diferentes. Primeiramente, \u00e9 poss\u00edvel que os ISP revisem para confirmar que exista alguma forma de cancelamento, e se n\u00e3o houver podem baixar sua reputa\u00e7\u00e3o. Al\u00e9m disso, se o assinante n\u00e3o conseguir cancelar, ir\u00e1 marcar sua mala direta como SPAM. E voc\u00ea tamb\u00e9m ser\u00e1 penalizado. Colocar o link de cancelamento \u00e9 gratuito. Se voc\u00ea n\u00e3o o colocar ir\u00e1 perder dinheiro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32806\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/motor.png\" alt=\"motor\" width=\"100\" height=\"80\" \/><\/p>\n<p><strong>7) A taxa de entrega depende inteiramente da ferramenta utilizada<\/strong><\/p>\n<p><em><strong>Falso.<\/strong><\/em> Usar uma boa ferramenta para enviar <a href=\"https:\/\/mailrelay.com\/pt\/\" target=\"_blank\" rel=\"noopener\">campanhas de email marketing<\/a> ajuda, isto a equipe da Mailrelay sabe, mas isto n\u00e3o \u00e9 tudo. Tamb\u00e9m \u00e9 preciso ter uma boa base de dados de assinantes. Atualizada e double opt-in. Envie conte\u00fados relevantes que sejam interessantes para os assinantes. Que estas campanhas tenham o formato adequado, o c\u00f3digo correto. Tudo conta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32808\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/tiempo.png\" alt=\"tiempo\" width=\"100\" height=\"80\" \/><\/p>\n<div style=\"float: left; width: 520px; height: 80px;\">\n<p><strong>8) A taxa de entrega n\u00e3o ir\u00e1 variar com o tempo<\/strong><\/p>\n<\/div>\n<p><em><strong>Falso. <\/strong><\/em>Existem muitos fatores que afetam a taxa de entrega. E \u00e9 claro que ser\u00e1 alterada com o tempo, voc\u00ea pode trabalhar para melhorar, mas ela poder\u00e1 piorar se as coisas n\u00e3o forem feitas corretamente. N\u00e3o \u00e9 algo que \u00e9 feito no in\u00edcio e n\u00e3o precisa mais ser revisado.podamos olvidar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-32802\" style=\"float: left;\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/thumbup.png\" alt=\"thumbup\" width=\"100\" height=\"80\" \/><\/p>\n<p><strong>9) ter um bom IP ou faixa de IP \u00e9 o suficiente, n\u00e3o h\u00e1 necessidade de fazer nada mais<\/strong><\/p>\n<p><em><strong>Falso<\/strong><\/em>. Obviamente, ter um bom IP, ou faixa de IP pode ajudar muito, mas \u00e0s vezes muito n\u00e3o \u00e9 suficiente, n\u00e3o \u00e9 o \u00fanico fator. \u00c9 um conceito similar ao ponto anterior. E tamb\u00e9m n\u00e3o \u00e9 certo.<\/p>\n<h3><\/h3>\n<p>Em resumo<\/p>\n<p>Enviar uma de mala direta \u00e9 um processo que pode ser afetado por m\u00faltiplos fatores, \u00e9 preciso levar todos eles em conta para obter bons resultados. A maioria dos erros discutidos neste artigo est\u00e1 relacionado com o fato de muitos usu\u00e1rios\u00a0 verem esse processo como algo est\u00e1tico ou mec\u00e2nico. Voc\u00ea ir\u00e1 usar uma ferramenta de email marketing, uma mensagem e uma lista de assinantes, voc\u00ea clica e as mensagens s\u00e3o enviadas e chegam ao seu destino.<\/p>\n<p>Mas existem muitos outros fatores a serem considerados. E estes fatores afetam o que finalmente chega, e o que ir\u00e1 ficar pelo caminho. Entre estes fatores, est\u00e3o os comentados neste artigo.<\/p>\n<p><strong>N\u00e3o se deixe enganar, tenha cuidado ao criar sua mala direta!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores. Cada pequeno detalhe pode afetar o resultado final. Temos que estar muito conscientes sobre eles! E revisar todos os pontos rigorosamente. A verdade \u00e9 que \u00e9 uma tarefa dif\u00edcil, uma vez que os ISP n\u00e3o enviam muitas informa\u00e7\u00f5es (normal, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-41710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9 mitos sobre taxa de entrega de mala direta - Mailrelay<\/title>\n<meta name=\"description\" content=\"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 mitos sobre taxa de entrega de mala direta - Mailrelay\" \/>\n<meta property=\"og:description\" content=\"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailrelay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mailrelay\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-12T05:42:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T12:11:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mailrelay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:site\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mailrelay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/\"},\"author\":{\"name\":\"Mailrelay\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\"},\"headline\":\"9 mitos sobre taxa de entrega de mala direta\",\"datePublished\":\"2015-05-12T05:42:42+00:00\",\"dateModified\":\"2023-09-12T12:11:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/\"},\"wordCount\":1218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/\",\"name\":\"9 mitos sobre taxa de entrega de mala direta - Mailrelay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg\",\"datePublished\":\"2015-05-12T05:42:42+00:00\",\"dateModified\":\"2023-09-12T12:11:52+00:00\",\"description\":\"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg\",\"width\":600,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2015\\\/05\\\/12\\\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 mitos sobre taxa de entrega de mala direta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"name\":\"Mailrelay\",\"description\":\"Mailrelay.com - Email Marketing Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\",\"name\":\"Mailrelay\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"width\":613,\"height\":291,\"caption\":\"Mailrelay\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mailrelay\\\/\",\"https:\\\/\\\/x.com\\\/mailrelay\",\"https:\\\/\\\/www.youtube.com\\\/mailrelay-email-marketing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\",\"name\":\"Mailrelay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"caption\":\"Mailrelay\"},\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/author\\\/mailrelay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 mitos sobre taxa de entrega de mala direta - Mailrelay","description":"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/","og_locale":"pt_BR","og_type":"article","og_title":"9 mitos sobre taxa de entrega de mala direta - Mailrelay","og_description":"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.","og_url":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/","og_site_name":"Mailrelay","article_publisher":"https:\/\/www.facebook.com\/Mailrelay\/","article_published_time":"2015-05-12T05:42:42+00:00","article_modified_time":"2023-09-12T12:11:52+00:00","og_image":[{"width":600,"height":500,"url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg","type":"image\/jpeg"}],"author":"Mailrelay","twitter_card":"summary_large_image","twitter_creator":"@mailrelay","twitter_site":"@mailrelay","twitter_misc":{"Escrito por":"Mailrelay","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#article","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/"},"author":{"name":"Mailrelay","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487"},"headline":"9 mitos sobre taxa de entrega de mala direta","datePublished":"2015-05-12T05:42:42+00:00","dateModified":"2023-09-12T12:11:52+00:00","mainEntityOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/"},"wordCount":1218,"commentCount":0,"publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/","url":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/","name":"9 mitos sobre taxa de entrega de mala direta - Mailrelay","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#primaryimage"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg","datePublished":"2015-05-12T05:42:42+00:00","dateModified":"2023-09-12T12:11:52+00:00","description":"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores.","breadcrumb":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#primaryimage","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg","width":600,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/mailrelay.com\/pt\/blog\/2015\/05\/12\/9-mitos-sobre-taxa-de-entrega-de-mala-direta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mailrelay.com\/pt\/"},{"@type":"ListItem","position":2,"name":"9 mitos sobre taxa de entrega de mala direta"}]},{"@type":"WebSite","@id":"https:\/\/mailrelay.com\/pt\/#website","url":"https:\/\/mailrelay.com\/pt\/","name":"Mailrelay","description":"Mailrelay.com - Email Marketing Software","publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mailrelay.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mailrelay.com\/pt\/#organization","name":"Mailrelay","url":"https:\/\/mailrelay.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","width":613,"height":291,"caption":"Mailrelay"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mailrelay\/","https:\/\/x.com\/mailrelay","https:\/\/www.youtube.com\/mailrelay-email-marketing"]},{"@type":"Person","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487","name":"Mailrelay","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","caption":"Mailrelay"},"url":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",600,500,false],"thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo-150x150.jpg",150,150,true],"medium":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo-300x250.jpg",300,250,true],"medium_large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",600,500,false],"large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",600,500,false],"1536x1536":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",600,500,false],"2048x2048":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",600,500,false],"testimonials":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo-110x92.jpg",110,92,true],"author-image":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",60,50,false],"yarpp-thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2015\/04\/9-mitos-de-la-entregabilidad-en-email-masivo.jpg",120,100,false]},"uagb_author_info":{"display_name":"Mailrelay","author_link":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"},"uagb_comment_info":0,"uagb_excerpt":"A taxa de entrega de uma mala direta \u00e9 uma vari\u00e1vel que depende de muitos fatores. Cada pequeno detalhe pode afetar o resultado final. Temos que estar muito conscientes sobre eles! E revisar todos os pontos rigorosamente. A verdade \u00e9 que \u00e9 uma tarefa dif\u00edcil, uma vez que os ISP n\u00e3o enviam muitas informa\u00e7\u00f5es (normal,&hellip;","_links":{"self":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/comments?post=41710"}],"version-history":[{"count":6,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41710\/revisions"}],"predecessor-version":[{"id":74648,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41710\/revisions\/74648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media\/32798"}],"wp:attachment":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media?parent=41710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/categories?post=41710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/tags?post=41710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}