{"id":41887,"date":"2017-11-22T14:00:34","date_gmt":"2017-11-22T14:00:34","guid":{"rendered":"https:\/\/wp.lvh.me\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/"},"modified":"2023-09-12T12:33:51","modified_gmt":"2023-09-12T12:33:51","slug":"contas-pausadas-ou-bloqueadas-razoes-e-solucoes","status":"publish","type":"post","link":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/","title":{"rendered":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es"},"content":{"rendered":"<p>Voc\u00ea acabou de criar sua conta na <strong>Mailrelay<\/strong> ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada? N\u00e3o se preocupe, neste post, vamos explicar os motivos e como resolv\u00ea-los.<\/p>\n<p><!--more--><\/p>\n<p>O sucesso ou fracasso de uma campanha de email marketing est\u00e1 diretamente afetado por m\u00faltiplos fatores que devem ser levados em considera\u00e7\u00e3o.<\/p>\n<p>Caso contr\u00e1rio, seus emails podem acabar na pasta de spam.<\/p>\n<p>O principal problema \u00e9 que os usu\u00e1rios n\u00e3o precisam saber de todos esses detalhes, e \u00e9 por isso que as ferramentas de email marketing <span style=\"text-decoration: underline;\"><em>devem garantir que eles sejam atendidos de forma adequada.<\/em><\/span><\/p>\n<p>Muitas vezes isso \u00e9 feito de uma maneira totalmente transparente para o usu\u00e1rio, como \u00e9 o caso da funcionalidade Smartdelivery.<\/p>\n<p>Mas outras vezes, \u00e9 necess\u00e1rio que o usu\u00e1rio execute uma a\u00e7\u00e3o e, portanto, deve ser notificado sobre o problema para poder resolv\u00ea-lo.<\/p>\n<p>Neste post, vamos explicar os motivos que podem fazer com que a sua conta da Mailrelay seja bloqueado.<\/p>\n\n<h2>Minha conta da Mailrelay est\u00e1 bloqueada ou pausada, o que posso fazer?<\/h2>\n<p>Sobretudo, n\u00e3o se preocupe.<\/p>\n<p>A primeira coisa que voc\u00ea deve fazer \u00e9 contactar o nosso <a href=\"https:\/\/mailrelay.com\/pt\/contato\/\">departamento de suporte<\/a> para revisar a sua conta (se eles ainda n\u00e3o fizeram isso).<\/p>\n<p>A partir da\u00ed, eles lhe dir\u00e3o o motivo espec\u00edfico para o bloqueio da conta e como ou o que voc\u00ea deve fazer para resolv\u00ea-lo.<\/p>\n<p>Ainda assim, h\u00e1 muitas causas frequentes que eu quero que voc\u00ea saiba, para que voc\u00ea veja que n\u00e3o \u00e9 um problema t\u00e3o grave.<\/p>\n<h3>\u25ba Dom\u00ednio recente<\/h3>\n<p>Esta \u00e9 uma das causas mais frequentes que levam ao bloqueio da conta, geralmente logo ap\u00f3s a sua cria\u00e7\u00e3o.<\/p>\n<p>O problema \u00e9 que o uso de dom\u00ednios recentemente registrados pode afetar negativamente suas campanhas de email marketing.<\/p>\n<p><strong>Como dissemos antes, usualmente, o webmaster n\u00e3o precisa saber disso.<\/strong><\/p>\n<p>Mas para evitar grandes problemas, que afetam a reputa\u00e7\u00e3o do dom\u00ednio, penalizando-o para futuras campanhas, o sistema pausa diretamente ou bloqueia a conta, impedindo que sejam enviadas newsletters que possam trazer problemas para o administrador do dom\u00ednio.<\/p>\n<p>Para resolver isto, o usu\u00e1rio pode entrar em contato com nossa equipe de suporte, que ir\u00e1 dar as instru\u00e7\u00f5es apropriadas para evitar esse problema.<\/p>\n<p>\u00c9, portanto, um mecanismo de seguran\u00e7a para impedir que o usu\u00e1rio, devido \u00e0 ignor\u00e2ncia, tenha problemas futuros.<\/p>\n<h3>\u25baWebsite dispon\u00edvel com informa\u00e7\u00f5es de contato<\/h3>\n<p>Este \u00e9 um requisito importante:<\/p>\n<p><strong>Todas as contas devem estar associada a um dom\u00ednio ativo, com website 100% publicado e com informa\u00e7\u00f5es de contato reais com o administrador da p\u00e1gina.<\/strong><\/p>\n<p>Isso \u00e9 muito importante, pois permite aos assinantes saberem como seus dados de contato foram obtidos, bem como o que deve fazer para solicitar o cancelamento, se desejar faz\u00ea-lo.<\/p>\n<p>Para todas as empresas este \u00e9 um padr\u00e3o b\u00e1sico de transpar\u00eancia, seja ou n\u00e3o obrigat\u00f3rio pela legisla\u00e7\u00e3o do seu pa\u00eds.<\/p>\n<p>Al\u00e9m de ser algo muito f\u00e1cil de cumprir, bem, praticamente n\u00e3o \u00e9 um requisito real, j\u00e1 que todas as empresas que tem um site ativo ter\u00e3o dados de contato no seu website.<\/p>\n<p>No entanto, esta informa\u00e7\u00e3o ajudar\u00e1 ao sistema para detectar potenciais spammers, porque eles geralmente n\u00e3o t\u00eam um site publicado. Desta forma, o sistema pode se proteger de potenciais spammers e garantir as as melhores taxas de entrega poss\u00edvel nas campanhas de email marketing de todos os usu\u00e1rios da ferramenta.<\/p>\n<p><strong>Algo que todos os usu\u00e1rios desejam \ud83d\ude42<\/strong><\/p>\n<p>Pode acontecer que, no seu caso, seja simplesmente que voc\u00ea ainda n\u00e3o finalizou o seu website, ele pode estar incompleto ou faltar algum requisito. N\u00e3o h\u00e1 problema, novamente, voc\u00ea apenas deve entrar em contato com nosso suporte que ir\u00e1 oferecer as informa\u00e7\u00f5es necess\u00e1rias para que a conta possa ser desbloqueada.<\/p>\n<h3>\u25baV\u00e1rias contas<\/h3>\n<p>Esta \u00e9 outra causa frequente de bloqueio ou contas pausadas.<\/p>\n<p><strong>Um usu\u00e1rio s\u00f3 pode ter uma conta gratuita, nunca ser\u00e1 permitido criar ou usar v\u00e1rias.<\/strong><\/p>\n<p>Mas \u00e9 claro, muitas vezes, os usu\u00e1rios n\u00e3o sabem disso. Afinal, quantas pessoas param para ler os <a href=\"https:\/\/mailrelay.com\/pt\/termos-de-uso\/\">termos de uso<\/a> de um servi\u00e7o antes de come\u00e7ar a us\u00e1-lo?<\/p>\n<p>O sistema tem filtros para detectar a cria\u00e7\u00e3o de mais de uma conta e, portanto, ir\u00e1 bloque\u00e1-las.<\/p>\n<p>Nesse caso, o usu\u00e1rio s\u00f3 precisa entrar em contato com o suporte e indicar qual conta ele ir\u00e1 manter. As outras, logicamente, ser\u00e3o exclu\u00eddas, depois de permitir que sejam feitas c\u00f3pias de seguran\u00e7a dos dados ou informa\u00e7\u00f5es relevantes.<\/p>\n<h3>\u25baCampanhas id\u00eanticas de v\u00e1rias contas<\/h3>\n<p>Isso geralmente est\u00e1 relacionado ao ponto anterior, embora nem sempre.<\/p>\n<p>\u00c0s vezes, um usu\u00e1rio pode querer ajudar outra empresa, enviando a mesma mala direta para a sua lista.<\/p>\n<p><strong>Isso nunca deve ser feito.<\/strong><\/p>\n<p>Por v\u00e1rios motivos, mas principalmente porque esses assinantes n\u00e3o se cadastraram para receber publicidade de outra empresa, eles n\u00e3o deram seu consentimento para isso, por isso muitos podem marcar a campanha de email marketing como spam, e o que foi feito para ajudar, pode terminar tornando-se um problema para ambas as empresas.<\/p>\n<p>Al\u00e9m disso, muitos spammers criam v\u00e1rias contas para tentar enviar usando todas elas.<\/p>\n<p>O sistema est\u00e1 preparado para detectar essas situa\u00e7\u00f5es e impedir que isto ocorra, antes que isto possa afetar os demais usu\u00e1rios.<\/p>\n<p>Em qualquer caso, nunca tente enviar mala direta em nome de outros dom\u00ednios.<\/p>\n<h3>\u25baAssuntos suscept\u00edveis de serem considerados spam<\/h3>\n<p>Este \u00e9 outro dos pontos considerados, assuntos como:<\/p>\n<ol>\n<li><strong>Teste<\/strong><\/li>\n<li><strong>Email de teste<\/strong><\/li>\n<li><strong>Newsletter<\/strong><\/li>\n<li><strong>Etc.<\/strong><\/li>\n<\/ol>\n<p>Juntamente com outros fatores que comentamos em outras ocasi\u00f5es, eles podem afetar a taxa de entrega dos emails.<\/p>\n<p>Tal como acontece com problemas de reputa\u00e7\u00e3o, \u00e9 melhor n\u00e3o arriscar, o sistema pode pausar a conta de forma preventiva, at\u00e9 que a equipe de suporte possa analis\u00e1-la detalhadamente.<\/p>\n<p><strong>Sempre tente usar assuntos t\u00e3o originais quanto poss\u00edvel!<\/strong><\/p>\n<h2>Em resumo<\/h2>\n<p>O sistema de revis\u00e3o de contas \u00e9 simplesmente uma outra ferramenta para garantir a efici\u00eancia da plataforma e detec\u00e7\u00e3o de spammers de forma ativa, garantindo o bom funcionamento da Mailrelay para todos os usu\u00e1rios.<\/p>\n<p>Isso realmente favorece todos os usu\u00e1rios, que gra\u00e7as a isso podem contar com uma entrega muito boa em todas as campanhas de email marketing.<\/p>\n<p>Em alguns casos, pode gerar falsos positivos, mas eles s\u00e3o muito raros e nesses casos, o usu\u00e1rio s\u00f3 precisar\u00e1 entrar em contato com a equipe de suporte, que ir\u00e1 indicar o que precisar\u00e1 ser feito para que o problema seja resolvido.<\/p>\n<p><strong>Depois disso, voc\u00ea poder\u00e1 continuar usando sua conta da Mailrelay de forma segura.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada? N\u00e3o se preocupe, neste post, vamos explicar os motivos e como resolv\u00ea-los.<\/p>\n","protected":false},"author":1,"featured_media":34734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-41887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay<\/title>\n<meta name=\"description\" content=\"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailrelay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mailrelay\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-22T14:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T12:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mailrelay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:site\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mailrelay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/\"},\"author\":{\"name\":\"Mailrelay\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\"},\"headline\":\"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es\",\"datePublished\":\"2017-11-22T14:00:34+00:00\",\"dateModified\":\"2023-09-12T12:33:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/\"},\"wordCount\":1130,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/mailrelay-seguridad-mailing.png\",\"articleSection\":[\"Uncategorized @pt\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/\",\"name\":\"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/mailrelay-seguridad-mailing.png\",\"datePublished\":\"2017-11-22T14:00:34+00:00\",\"dateModified\":\"2023-09-12T12:33:51+00:00\",\"description\":\"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/mailrelay-seguridad-mailing.png\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/mailrelay-seguridad-mailing.png\",\"width\":630,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2017\\\/11\\\/22\\\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"name\":\"Mailrelay\",\"description\":\"Mailrelay.com - Email Marketing Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\",\"name\":\"Mailrelay\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"width\":613,\"height\":291,\"caption\":\"Mailrelay\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mailrelay\\\/\",\"https:\\\/\\\/x.com\\\/mailrelay\",\"https:\\\/\\\/www.youtube.com\\\/mailrelay-email-marketing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\",\"name\":\"Mailrelay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"caption\":\"Mailrelay\"},\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/author\\\/mailrelay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay","description":"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay","og_description":"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?","og_url":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/","og_site_name":"Mailrelay","article_publisher":"https:\/\/www.facebook.com\/Mailrelay\/","article_published_time":"2017-11-22T14:00:34+00:00","article_modified_time":"2023-09-12T12:33:51+00:00","og_image":[{"width":630,"height":340,"url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png","type":"image\/png"}],"author":"Mailrelay","twitter_card":"summary_large_image","twitter_creator":"@mailrelay","twitter_site":"@mailrelay","twitter_misc":{"Escrito por":"Mailrelay","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#article","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/"},"author":{"name":"Mailrelay","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487"},"headline":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es","datePublished":"2017-11-22T14:00:34+00:00","dateModified":"2023-09-12T12:33:51+00:00","mainEntityOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/"},"wordCount":1130,"commentCount":0,"publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png","articleSection":["Uncategorized @pt"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/","url":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/","name":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es - Mailrelay","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#primaryimage"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png","datePublished":"2017-11-22T14:00:34+00:00","dateModified":"2023-09-12T12:33:51+00:00","description":"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada?","breadcrumb":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#primaryimage","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png","width":630,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/mailrelay.com\/pt\/blog\/2017\/11\/22\/contas-pausadas-ou-bloqueadas-razoes-e-solucoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mailrelay.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Contas pausadas ou bloqueadas, raz\u00f5es e solu\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/mailrelay.com\/pt\/#website","url":"https:\/\/mailrelay.com\/pt\/","name":"Mailrelay","description":"Mailrelay.com - Email Marketing Software","publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mailrelay.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mailrelay.com\/pt\/#organization","name":"Mailrelay","url":"https:\/\/mailrelay.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","width":613,"height":291,"caption":"Mailrelay"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mailrelay\/","https:\/\/x.com\/mailrelay","https:\/\/www.youtube.com\/mailrelay-email-marketing"]},{"@type":"Person","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487","name":"Mailrelay","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","caption":"Mailrelay"},"url":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",630,340,false],"thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing-150x150.png",150,150,true],"medium":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing-300x162.png",300,162,true],"medium_large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",630,340,false],"large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",630,340,false],"1536x1536":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",630,340,false],"2048x2048":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",630,340,false],"testimonials":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing-110x59.png",110,59,true],"author-image":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",60,32,false],"yarpp-thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/11\/mailrelay-seguridad-mailing.png",120,65,false]},"uagb_author_info":{"display_name":"Mailrelay","author_link":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"},"uagb_comment_info":2,"uagb_excerpt":"Voc\u00ea acabou de criar sua conta na Mailrelay ou est\u00e1 enviando uma campanha de email marketing, mas voc\u00ea est\u00e1 recebendo uma mensagem informando que sua conta est\u00e1 pausada ou bloqueada? N\u00e3o se preocupe, neste post, vamos explicar os motivos e como resolv\u00ea-los.","_links":{"self":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/comments?post=41887"}],"version-history":[{"count":8,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41887\/revisions"}],"predecessor-version":[{"id":74676,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/41887\/revisions\/74676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media\/34734"}],"wp:attachment":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media?parent=41887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/categories?post=41887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/tags?post=41887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}