{"id":46712,"date":"2020-09-01T07:06:34","date_gmt":"2020-09-01T07:06:34","guid":{"rendered":"https:\/\/mailrelay.com\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/"},"modified":"2022-12-28T12:53:37","modified_gmt":"2022-12-28T12:53:37","slug":"7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads","status":"publish","type":"post","link":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/","title":{"rendered":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads"},"content":{"rendered":"<p>Uma das \u00e1reas mais negligenciadas por muitas empresas no Google Ads \u00e9 a <strong>segmenta\u00e7\u00e3o de audi\u00eancia.<\/strong> A cada ano que passa, o Google oferece novas segmenta\u00e7\u00f5es de p\u00fablico e maneiras de alcan\u00e7ar seus clientes em potencial, por isso \u00e9 normal nem sempre estar a par de todas as not\u00edcias. Por\u00e9m, a utiliza\u00e7\u00e3o incorreta da segmenta\u00e7\u00e3o de audi\u00eancia poderia afetar o resultado da campanha, j\u00e1 que voc\u00ea estaria gastando dinheiro com usu\u00e1rios que n\u00e3o est\u00e3o interessados no produto, aumentando o custo final do <a href=\"https:\/\/mailrelay.com\/pt\/blog\/2018\/06\/27\/o-que-e-cpm-cpc-cpl-cpa-e-cpi-e-qual-a-diferenca-entre-estes-conceitos\/\" target=\"_blank\" rel=\"noopener\">CPC<\/a>.<\/p>\n<p>Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos, por isso vamos explicar uma s\u00e9rie de t\u00e1ticas que voc\u00ea poderia aplicar em sua estrat\u00e9gia:<\/p>\n\n<h2>1. P\u00fablicos relacionados para aumentar o reconhecimento da marca<\/h2>\n<p>Toda boa estrat\u00e9gia de marketing deve ter objetivos distintos que contemplem todas as etapas pelos quais o usu\u00e1rio passa, desde o reconhecimento da necessidade de compra at\u00e9 a venda final; as famosas fases do funil de vendas. O Google Ads n\u00e3o \u00e9 diferente de outros canais de marketing e tamb\u00e9m \u00e9 conveniente estruturar suas campanhas de acordo com o estado do funil de vendas que voc\u00ea deseja alcan\u00e7ar.<\/p>\n<p>Embora muitas empresas queiram obter convers\u00f5es diretamente, a realidade \u00e9 que um usu\u00e1rio geralmente leva mais tempo para confiar em voc\u00ea antes de comprar o que voc\u00ea oferece (especialmente se voc\u00ea est\u00e1 tentando vender um produto de custo elevado). Portanto, em primeiro lugar \u00e9 conveniente criar campanhas de reconhecimento de marca e divulgar sua empresa. Para isso podemos utilizar os p\u00fablicos-alvo \u00a0relacionados ao seu neg\u00f3cio, pois s\u00e3o listas que incluem usu\u00e1rios que, a partir de seu hist\u00f3rico de navega\u00e7\u00e3o, possuem interesses semelhantes aos produtos que voc\u00ea oferece.<\/p>\n<p>Por exemplo, se voc\u00ea for uma ag\u00eancia de viagens, seria relevante criar uma campanha com os p\u00fablicos relacionados de &#8220;Entusiastas de viagens&#8221;, &#8220;Viajantes de praia&#8221;, &#8220;Viajantes em fam\u00edlia&#8221;, &#8220;Viajantes de luxo&#8221; etc. Essas listas n\u00e3o incluem usu\u00e1rios que desejam viajar hoje, mas que gostam do tema viagens; Portanto, para uma ag\u00eancia de viagens, seria\u00a0 interessante divulgar o seu neg\u00f3cio, criando uma estrat\u00e9gia para atrair estes usu\u00e1rios e convenc\u00ea-los a avan\u00e7ar atrav\u00e9s do funil de vendas e assim, quando quiserem viajar, v\u00e3o levar sua marca em considera\u00e7\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40934 size-full\" title=\"ejemplos de audiencias google ads\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-google-ads.jpg\" alt=\"ejemplos de audiencias google ads\" width=\"361\" height=\"279\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-google-ads.jpg 361w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-google-ads-300x232.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-google-ads-110x85.jpg 110w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><\/p>\n<h2>2. P\u00fablico com inten\u00e7\u00e3o de compra, para usu\u00e1rios prontos para a convers\u00e3o<\/h2>\n<p>Por outro lado, temos os p\u00fablicos-alvo de inten\u00e7\u00e3o de compra, que s\u00e3o listas de usu\u00e1rios que buscam ativamente adquirir um tipo espec\u00edfico de produto ou servi\u00e7o. Portanto, \u00e9 conveniente aproveitar esses p\u00fablicos em sua campanha com foco em convers\u00e3o, pois ajuda a segmentar o alcance, obter cliques mais qualificados e reduzir custos.<\/p>\n<p>Por exemplo, digamos que sua empresa venda televisores; Existe um p\u00fablico com inten\u00e7\u00e3o de compra denominada \u201cTelevisores\u201d que re\u00fane usu\u00e1rios que, devido \u00e0 informa\u00e7\u00e3o coletada pelos buscadores, pretendem comprar TVs. Portanto, voc\u00ea pode segmentar o alcance de forma muito eficiente e contribuir para taxas de convers\u00e3o mais altas, pois estaremos exibindo o an\u00fancio para algu\u00e9m que deseja comprar o produto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40936\" title=\"ejemplos de audiencias de venta google ads\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-de-venta-google-ads.jpg\" alt=\"ejemplos de audiencias de venta google ads\" width=\"600\" height=\"252\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-de-venta-google-ads.jpg 666w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-de-venta-google-ads-300x126.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/ejemplos-de-audiencias-de-venta-google-ads-110x46.jpg 110w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2>3.\u00a0Campanha com p\u00fablicos em observa\u00e7\u00e3o ou segmenta\u00e7\u00e3o de acordo com seus objetivos<\/h2>\n<p>Muitos especialistas em SEM ignoram a diferen\u00e7a entre essas duas op\u00e7\u00f5es, pois as informa\u00e7\u00f5es que o Google fornece sobre isso podem ser um tanto amb\u00edguas e confusas. Por\u00e9m, \u00e9 importante saber a diferen\u00e7a, porque dependendo de como o p\u00fablico foi selecionado, os resultados podem ser muito diferentes.<\/p>\n<p>Dependendo de como sua campanha foi configurada, o investimento aumentar\u00e1 quando os usu\u00e1rios pertencentes as listas criadas buscarem os termos relevantes para o seu neg\u00f3cio, mas os usu\u00e1rios que n\u00e3o pertencem a essa lista n\u00e3o s\u00e3o exclu\u00eddos. Por outro lado, com o modo de segmenta\u00e7\u00e3o, qualquer usu\u00e1rio que n\u00e3o perten\u00e7a \u00e0s listas de p\u00fablico que voc\u00ea implementou ser\u00e3o exclu\u00eddos.<\/p>\n<p>O modo que voc\u00ea usa depende muito dos seus objetivos: se voc\u00ea quer alto volume de cliques, a <strong>observa\u00e7\u00e3o \u00e9 a melhor op\u00e7\u00e3o;<\/strong> Por outro lado, se voc\u00ea deseja ter um tr\u00e1fego mais qualificado e reduzir custos, seria melhor trabalhar com segmenta\u00e7\u00e3o.<\/p>\n<h2>4. Campanhas de remarketing no modo de segmenta\u00e7\u00e3o<\/h2>\n<p>Como acabamos de explicar, o modo de segmenta\u00e7\u00e3o nos permite focalizar a mensagem que queremos transmitir a um grupo de pessoas espec\u00edficas. Ao criar campanhas com listas de remarketing no modo de segmenta\u00e7\u00e3o, podemos direcionar nossos an\u00fancios para pessoas que j\u00e1 demonstraram interesse no produto ou servi\u00e7o que oferecemos; o que nos permite usar chamadas \u00e0 a\u00e7\u00e3o mais incisivas, incluindo descri\u00e7\u00f5es mais focadas nas vendas ou <strong>implementar as palavras-chave<\/strong> pertencentes \u00e0 parte inferior do funil de vendas. \u00c9 conveniente adicionar tamb\u00e9m listas de exclus\u00e3o com usu\u00e1rios que j\u00e1 foram convertidos, pois queremos alcan\u00e7ar apenas aqueles que demonstraram interesse, mas n\u00e3o conclu\u00edram a compra.<\/p>\n<p>Antes de implementar esta estrat\u00e9gia, voc\u00ea deve ter em mente que para ativar as listas de remarketing voc\u00ea precisa de pelo menos 1000 usu\u00e1rios ativos, ent\u00e3o \u00e9 um tipo de campanha que geralmente \u00e9 criada quando sua conta do Google Ads j\u00e1 est\u00e1 recebendo tr\u00e1fego h\u00e1 v\u00e1rios meses. <strong>Voc\u00ea pode criar diferentes listas de remarketing e moldar o tom de seus an\u00fancios de acordo com o status no funil de vendas<\/strong> ao qual o usu\u00e1rio pertence (abandonar o carrinho de compras, inscri\u00e7\u00f5es para demonstra\u00e7\u00e3o gratuita, mais de X minutos na p\u00e1gina de destino etc.).<\/p>\n<h2>5. P\u00fablicos-alvo personalizados em display e v\u00eddeo<\/h2>\n<p>Uma das funcionalidades de display e v\u00eddeo mais desconhecidas s\u00e3o os p\u00fablicos alvo personalizados. O pouco uso que lhes \u00e9 dado \u00e9 uma pena, pois permitem incluir um amplo leque de par\u00e2metros e vari\u00e1veis para definir um novo p\u00fablico de grande relev\u00e2ncia para o seu neg\u00f3cio. Voc\u00ea pode adicionar interesses, URLs, sites e aplicativos, embora n\u00e3o seja necess\u00e1rio incluir todos os par\u00e2metros para ativar esta configura\u00e7\u00e3o.<\/p>\n<p>Ao trabalhar com p\u00fablicos-alvo personalizados, voc\u00ea poder\u00e1 segmentar o alcance daqueles usu\u00e1rios que atendem a mais de uma condi\u00e7\u00e3o que os torna relevantes para o que voc\u00ea oferece. Ou seja, \u00e9 uma boa forma de aplicar v\u00e1rios filtros que garantam tr\u00e1fego qualificado e efici\u00eancia no investimento para ter um ROI positivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40938 size-full\" title=\"google ads audiencia af\u00edn\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencia-afin.jpg\" alt=\"google ads audiencia af\u00edn\" width=\"599\" height=\"382\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencia-afin.jpg 599w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencia-afin-300x191.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencia-afin-110x70.jpg 110w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/p>\n<p>Al\u00e9m disso, o Google nos apresenta v\u00e1rios dados com base nos par\u00e2metros que inclu\u00edmos para que possamos conhecer melhor o perfil do usu\u00e1rio que vamos atingir, como o tamanho da audi\u00eancia, dados demogr\u00e1ficos, ou temas de interesse.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40940 size-full\" title=\"tama\u00f1o audiencia af\u00edn\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/tamano-audiencia-afin.jpg\" alt=\"tama\u00f1o audiencia af\u00edn\" width=\"476\" height=\"458\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/tamano-audiencia-afin.jpg 476w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/tamano-audiencia-afin-300x289.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/tamano-audiencia-afin-110x106.jpg 110w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/><\/p>\n<h2>6.\u00a0Alcance o perfil do seu buyer persona<\/h2>\n<p>Existem tantas op\u00e7\u00f5es no Google Ads que muitas contas esquecem a mais b\u00e1sica: alcan\u00e7ar seu buyer persona. Para conhecer o perfil do seu comprador ideal, \u00e9 bom que voc\u00ea fa\u00e7a um <a href=\"https:\/\/mailrelay.com\/pt\/blog\/2018\/09\/06\/como-fazer-um-estudo-de-mercado-passo-a-passo\/\" target=\"_blank\" rel=\"noopener\">estudo de mercado<\/a> e at\u00e9 converse com os funcion\u00e1rios que t\u00eam um contato mais direto com o cliente para obter diferentes pontos de vista.<\/p>\n<p>Al\u00e9m disso, se voc\u00ea tem tr\u00e1fego org\u00e2nico em seu site, pode usar o <strong>Analytics para obter informa\u00e7\u00f5es sobre faixa et\u00e1ria<\/strong>, g\u00eanero, poder de compra e outros dados demogr\u00e1ficos de seus clientes. Dessa forma, voc\u00ea pode definir grupos para esses atributos no Google Ads e alcan\u00e7ar os usu\u00e1rios que atendem \u00e0s caracter\u00edsticas do seu buyer persona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-40942\" title=\"audiencias por edad\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencias-por-edad.jpg\" alt=\"audiencias por edad\" width=\"600\" height=\"173\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencias-por-edad.jpg 909w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencias-por-edad-300x86.jpg 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencias-por-edad-768x221.jpg 768w, https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/audiencias-por-edad-110x32.jpg 110w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2>7. Ajustes de Grupo com base na l\u00f3gica de neg\u00f3cios e desempenho<\/h2>\n<p>Depois de implementar sua estrat\u00e9gia de p\u00fablico com base na l\u00f3gica de neg\u00f3cios e mercado, n\u00e3o podemos ignor\u00e1-los. A pr\u00f3xima etapa \u00e9 ajustar o grupo, com base no desempenho e nos KPIs.<\/p>\n<p>Por exemplo, se sua meta atual \u00e9 aumentar as vendas de um determinado produto, voc\u00ea pode aumentar os lances dos p\u00fablicos que t\u00eam convers\u00f5es e perdem impress\u00f5es de pesquisa por classifica\u00e7\u00e3o; e, por outro lado, diminuir os lances dos p\u00fablicos que custam mais dinheiro e n\u00e3o convertem. Essa \u00e9 a mesma l\u00f3gica dos ajustes de lance de palavra-chave, mas muitos gerentes de conta esquecem os p\u00fablicos-alvo e n\u00e3o trabalham com eles com a mesma frequ\u00eancia que as palavras-chave; o que \u00e9 um grande erro, j\u00e1 que o Google est\u00e1 cada vez mais dando mais import\u00e2ncia ao p\u00fablico do que \u00e0s palavras-chave.<\/p>\n<h2>Em definitivo\u2026<\/h2>\n<p>Como podemos ver, existem muitas estrat\u00e9gias que podemos aplicar usando os p\u00fablicos-alvo no Google Ads. Neste artigo, mostramos alguns exemplos, mas as combina\u00e7\u00f5es de listas que voc\u00ea pode criar s\u00e3o ilimitadas.<\/p>\n<p><strong>Para resumir, estes s\u00e3o os pontos que cobrimos:<\/strong><\/p>\n<ul>\n<li>P\u00fablicos relacionados para divulgar a marca do seu neg\u00f3cio.<\/li>\n<li>P\u00fablico-alvo com inten\u00e7\u00e3o de compra para promover seus produtos ou servi\u00e7os para os clientes em potencial que desejam converter.<\/li>\n<li>Modo de observa\u00e7\u00e3o ou segmenta\u00e7\u00e3o de acordo com o alcance que deseja obter.<\/li>\n<li>Campanhas de remarketing para refinar seus an\u00fancios com base na experi\u00eancia do usu\u00e1rio com sua empresa.<\/li>\n<li>P\u00fablicos-alvo de display e v\u00eddeo personalizados com par\u00e2metros relevantes para o seu neg\u00f3cio.<\/li>\n<li>Defina as caracter\u00edsticas do seu buyer persona no Google Ads.<\/li>\n<li>Aumente e diminua os lances de p\u00fablico-alvo com base nos KPIs desejados.<\/li>\n<\/ul>\n<h5 style=\"text-align: right;\"><em>Traduzido Por Micheli.<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Uma das \u00e1reas mais negligenciadas por muitas empresas no Google Ads \u00e9 a segmenta\u00e7\u00e3o de audi\u00eancia. A cada ano que passa, o Google oferece novas segmenta\u00e7\u00f5es de p\u00fablico e maneiras de alcan\u00e7ar seus clientes em potencial, por isso \u00e9 normal nem sempre estar a par de todas as not\u00edcias. Por\u00e9m, a utiliza\u00e7\u00e3o incorreta da segmenta\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-46712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay<\/title>\n<meta name=\"description\" content=\"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay\" \/>\n<meta property=\"og:description\" content=\"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailrelay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mailrelay\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T07:06:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T12:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mailrelay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:site\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mailrelay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/\"},\"author\":{\"name\":\"Mailrelay\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\"},\"headline\":\"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads\",\"datePublished\":\"2020-09-01T07:06:34+00:00\",\"dateModified\":\"2022-12-28T12:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/\"},\"wordCount\":1610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png\",\"articleSection\":[\"Uncategorized @pt\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/\",\"name\":\"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png\",\"datePublished\":\"2020-09-01T07:06:34+00:00\",\"dateModified\":\"2022-12-28T12:53:37+00:00\",\"description\":\"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png\",\"width\":630,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2020\\\/09\\\/01\\\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"name\":\"Mailrelay\",\"description\":\"Mailrelay.com - Email Marketing Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\",\"name\":\"Mailrelay\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"width\":613,\"height\":291,\"caption\":\"Mailrelay\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mailrelay\\\/\",\"https:\\\/\\\/x.com\\\/mailrelay\",\"https:\\\/\\\/www.youtube.com\\\/mailrelay-email-marketing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\",\"name\":\"Mailrelay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"caption\":\"Mailrelay\"},\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/author\\\/mailrelay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay","description":"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/","og_locale":"pt_BR","og_type":"article","og_title":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay","og_description":"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos","og_url":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/","og_site_name":"Mailrelay","article_publisher":"https:\/\/www.facebook.com\/Mailrelay\/","article_published_time":"2020-09-01T07:06:34+00:00","article_modified_time":"2022-12-28T12:53:37+00:00","og_image":[{"width":630,"height":340,"url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png","type":"image\/png"}],"author":"Mailrelay","twitter_card":"summary_large_image","twitter_creator":"@mailrelay","twitter_site":"@mailrelay","twitter_misc":{"Escrito por":"Mailrelay","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#article","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/"},"author":{"name":"Mailrelay","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487"},"headline":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads","datePublished":"2020-09-01T07:06:34+00:00","dateModified":"2022-12-28T12:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/"},"wordCount":1610,"commentCount":0,"publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png","articleSection":["Uncategorized @pt"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/","url":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/","name":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads - Mailrelay","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#primaryimage"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png","datePublished":"2020-09-01T07:06:34+00:00","dateModified":"2022-12-28T12:53:37+00:00","description":"Para melhorar o ROI de seus custos de SEM, \u00e9 essencial conhecer as diferentes estrat\u00e9gias que voc\u00ea pode aplicar por meio da implementa\u00e7\u00e3o de p\u00fablicos","breadcrumb":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#primaryimage","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png","width":630,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/mailrelay.com\/pt\/blog\/2020\/09\/01\/7-estrategias-que-voce-provavelmente-desconhece-sobre-os-publicos-do-google-ads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mailrelay.com\/pt\/"},{"@type":"ListItem","position":2,"name":"7 estrat\u00e9gias que voc\u00ea provavelmente desconhece sobre os p\u00fablicos do Google Ads"}]},{"@type":"WebSite","@id":"https:\/\/mailrelay.com\/pt\/#website","url":"https:\/\/mailrelay.com\/pt\/","name":"Mailrelay","description":"Mailrelay.com - Email Marketing Software","publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mailrelay.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mailrelay.com\/pt\/#organization","name":"Mailrelay","url":"https:\/\/mailrelay.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","width":613,"height":291,"caption":"Mailrelay"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mailrelay\/","https:\/\/x.com\/mailrelay","https:\/\/www.youtube.com\/mailrelay-email-marketing"]},{"@type":"Person","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487","name":"Mailrelay","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","caption":"Mailrelay"},"url":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",630,340,false],"thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads-150x150.png",150,150,true],"medium":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads-300x162.png",300,162,true],"medium_large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",630,340,false],"large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",630,340,false],"1536x1536":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",630,340,false],"2048x2048":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",630,340,false],"testimonials":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads-110x59.png",110,59,true],"author-image":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",60,32,false],"yarpp-thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2020\/08\/7-Estrategias-que-Probablemente-Desconozcas-sobre-las-Audiencias-de-Google-Ads.png",120,65,false]},"uagb_author_info":{"display_name":"Mailrelay","author_link":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"},"uagb_comment_info":1,"uagb_excerpt":"Uma das \u00e1reas mais negligenciadas por muitas empresas no Google Ads \u00e9 a segmenta\u00e7\u00e3o de audi\u00eancia. A cada ano que passa, o Google oferece novas segmenta\u00e7\u00f5es de p\u00fablico e maneiras de alcan\u00e7ar seus clientes em potencial, por isso \u00e9 normal nem sempre estar a par de todas as not\u00edcias. Por\u00e9m, a utiliza\u00e7\u00e3o incorreta da segmenta\u00e7\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/46712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/comments?post=46712"}],"version-history":[{"count":5,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/46712\/revisions"}],"predecessor-version":[{"id":60605,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/46712\/revisions\/60605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media\/27933"}],"wp:attachment":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media?parent=46712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/categories?post=46712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/tags?post=46712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}