{"id":49653,"date":"2022-05-13T20:40:24","date_gmt":"2022-05-13T20:40:24","guid":{"rendered":"https:\/\/mailrelay.com\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/"},"modified":"2022-12-28T10:52:31","modified_gmt":"2022-12-28T10:52:31","slug":"como-sera-o-marketing-digital-sem-cookies","status":"publish","type":"post","link":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/","title":{"rendered":"Como ser\u00e1 o marketing digital sem cookies?"},"content":{"rendered":"<p>Nos \u00faltimos anos, as empresas tiraram muitas vantagens das <strong>informa\u00e7\u00f5es proporcionadas pelos usu\u00e1rios atrav\u00e9s dos cookies<\/strong>, que foram criados em 1994 e foram uma ferramenta fundamental para criar an\u00fancios e lan\u00e7ar campanhas publicit\u00e1rias. Portanto, avan\u00e7ar para o Marketing Digital sem cookies \u00e9 motivo de grande preocupa\u00e7\u00e3o para muitos deles.<\/p>\n<p>E n\u00e3o s\u00f3 as empresas ser\u00e3o afetadas, <strong>Cada vez mais usu\u00e1rios est\u00e3o se sentindo mais preocupados e incomodados<\/strong> com a invas\u00e3o de privacidade causada pelo uso deste tipo de cookies <strong>(cookies de terceiros)<\/strong> por isso neste artigo vamos nos aprofundar no conceito dos cookies e em como o marketing digital ser\u00e1 afetado pela elimina\u00e7\u00e3o desta tecnologia.<\/p>\n<p>Voc\u00ea j\u00e1 ouviu falar sobre como ser\u00e1 o Marketing Digital sem cookies? Continue lendo para saber todos os detalhes desta nova iniciativa.<\/p>\n\n<h2>O que s\u00e3o cookies?<\/h2>\n<p><strong>Um cookie<\/strong> \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.<\/p>\n<p>Destinam-se a melhorar a qualidade do servi\u00e7o oferecido e, sobretudo, a experi\u00eancia do usu\u00e1rio. Este tipo de arquivo \u00e9 usado em todos os websites e navegadores e todos os Usu\u00e1rios da Internet s\u00e3o monitorados atrav\u00e9s de Cookies.<\/p>\n<p><strong>O objetivo dos cookies<\/strong> \u00e9 armazenar a movimenta\u00e7\u00e3o do usu\u00e1rio no seu navegador para acessar certas p\u00e1ginas web, <strong>Bem como para &#8220;recordar&#8221; o acesso realizado<\/strong> (sejam senhas, question\u00e1rios, buscas, etc.) e identificar qu\u00e1is s\u00e3o as p\u00e1ginas que costuma visitar com mais frequ\u00eancia.<\/p>\n<p>Desta forma, os sites reconhecem o usu\u00e1rio que est\u00e1 acessando a p\u00e1gina e automaticamente lembram quem \u00e9, quando foi a \u00faltima vez que entrou e o que estava fazendo no site.<\/p>\n<p><strong>Por esta raz\u00e3o, pode-se dizer que os cookies ajudam<\/strong> para que o carregamento das p\u00e1ginas web seja mais r\u00e1pido e para que os resultados se adaptem mais precisamente aos gostos e necessidades do usu\u00e1rio, permitindo-lhe manter-se conectado sem ter de iniciar sess\u00e3o ou registrar-se sempre que pretender acessar um site.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-38490 size-full\" title=\"Qual \u00e9 a import\u00e2ncia dos cookies no Marketing Digital?\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2016\/03\/Politica-de-cookies.png\" alt=\"Qual \u00e9 a import\u00e2ncia dos cookies no Marketing Digital?\" width=\"630\" height=\"340\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2016\/03\/Politica-de-cookies.png 630w, https:\/\/mailrelay.com\/wp-content\/uploads\/2016\/03\/Politica-de-cookies-300x162.png 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2016\/03\/Politica-de-cookies-110x59.png 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<h2>Qual \u00e9 a import\u00e2ncia dos cookies no Marketing Digital?<\/h2>\n<p><strong>Os cookies<\/strong> podem ser usados para diferentes finalidades que pretendem ajudar e facilitar a navega\u00e7\u00e3o do usu\u00e1rio, mas o problema est\u00e1 no uso inapropriado destas informa\u00e7\u00f5es que podem ser caracterizadas como invas\u00e3o da privacidade do usu\u00e1rio.<\/p>\n<p>No entanto,<strong> la import\u00e2ncia dos cookies no Marketing Digital<\/strong> \u00e9 relevante, j\u00e1 que buscam aperfei\u00e7oar a experi\u00eancia do usu\u00e1rio, al\u00e9m de melhorar o conte\u00fado e os an\u00fancios direcionados para cada visitante.<\/p>\n<p>Para melhor explicar a relev\u00e2ncia e as <a href=\"https:\/\/mailrelay.com\/pt\/blog\/2022\/10\/18\/caracteristicas-detalhadas-da-mailrelay-todas-as-vantagens-oferecidas-pelo-programa-de-email-marketing-gratis\/\" target=\"_blank\" rel=\"noopener\">caracter\u00edsticas<\/a> destes, nos pr\u00f3ximos par\u00e1grafos iremos dividi-los pelos diferentes tipos de cookies que existem.<\/p>\n<h2>Tipos de cookies<\/h2>\n<p>Existem diferentes <strong>tipos de cookies<\/strong> que s\u00e3o usados dependendo do consentimento do usu\u00e1rio, incluindo cookies pr\u00f3prias de cada website ou de terceiros e o prop\u00f3sito de cada um deles.<\/p>\n<h3>\u00b7 O consentimento:<\/h3>\n<p><strong>&#8211; Cookies com exce\u00e7\u00e3o<\/strong><\/p>\n<p>Trata-se de <strong>cookies de se\u00e7\u00e3o<\/strong> e entrada do usu\u00e1rio, ou seja, s\u00e3o cookies que n\u00e3o requerem o consentimento expresso do visitante para que sejam aceitos. Este tipo de cookie melhora o funcionamento do site, portanto, como dissemos anteriormente, eles podem ser usados \u200b\u200bsem o consentimento pr\u00e9vio do usu\u00e1rio.<\/p>\n<p><strong>&#8211; Cookies que requerem consentimento<\/strong><\/p>\n<p>O restante dos <strong>cookies<\/strong> usados pelo website s\u00e3o os requerem<strong> consentimento<\/strong>, por isso o usu\u00e1rio dever\u00e1 aceit\u00e1-las para que possam ser usados, o que significa que o usu\u00e1rio dever\u00e1 ser notificado previamente. Al\u00e9m disso, este ter\u00e1 a op\u00e7\u00e3o de acepit\u00e1-las ou n\u00e3o de uma forma clara e direta.<\/p>\n<h3>\u00b7 A entidade que os gerencia:<\/h3>\n<p>Dependendo do dom\u00ednio ou servidor para o qual os cookies s\u00e3o direcionados, ou seja, dependendo da corpora\u00e7\u00e3o que os administra e trata seus dados e informa\u00e7\u00f5es, encontramos dois tipos diferentes:<\/p>\n<p><strong>&#8211; Cookies originais<\/strong><\/p>\n<p>Tamb\u00e9n conhecidos como <strong>cookies pr\u00f3prios<\/strong>.<\/p>\n<p>Como o pr\u00f3prio nome indica, s\u00e3o os cookies que s\u00e3o gerados pela pr\u00f3pria p\u00e1gina web que o usu\u00e1rio est\u00e1 visitando, que se destinam a melhorar o seu funcionamento e melhorar a experi\u00eancia do usu\u00e1rio no website.<\/p>\n<p>Estes cookies s\u00e3o usados com a finalidade de <strong>calcular o tr\u00e1fego do dom\u00ednio<\/strong>, o n\u00famero de p\u00e1ginas visitadas, o n\u00famero de usu\u00e1rios, etc. Al\u00e9m disso, os respons\u00e1veis pelos cookies pr\u00f3prios os utilizam para cri<strong>ar campanhas e an\u00fancios<\/strong> direcionados ao seu p\u00fablico alvo e fazem isto como, por exemplo, atrav\u00e9s da f<strong>erramenta do Google Analytics.<\/strong><\/p>\n<p><strong>&#8211; Cookies de terceiros<\/strong><\/p>\n<p><strong>Os cookies de terceiros<\/strong> s\u00e3o aqueles que n\u00e3o s\u00e3o gerados pela pr\u00f3pria p\u00e1gina web, mas sim pelos servidores ou provedores externos ao dom\u00ednio. Referem-se aos an\u00fancios que o usu\u00e1rio pode encontrar ao entrar em uma determinada p\u00e1gina da web e podem ser bloqueados por ele sem nenhum problema.<\/p>\n<p>No entanto, se forem aceitos, estes cookies ir\u00e3o rastrear e salvar informa\u00e7\u00f5es do usu\u00e1rio para oferecer-lhes <strong>an\u00fancios mais personalizados e eficazes.<\/strong><\/p>\n<h3>\u00b7 Seu prop\u00f3sito:<\/h3>\n<p>Os cookies tamb\u00e9m podem ser classificados de acordo com a finalidade com que obt\u00eam as informa\u00e7\u00f5es do usu\u00e1rio, podendo ser:<\/p>\n<p><strong>&#8211; Cookies t\u00e9cnicos ou estritamente necess\u00e1rios<\/strong><\/p>\n<p>S\u00e3o aqueles que permitem ao usu\u00e1rio navegar nas p\u00e1ginas da web que acessa e, desta forma, selecionar as diferentes op\u00e7\u00f5es e utilizar os diversos servi\u00e7os que oferecem, como, por exemplo, identificar o login de um usu\u00e1rio, lembrar os produtos que foram adicionados ao carrinho em uma sess\u00e3o anterior, etc.<\/p>\n<p><strong>&#8211; Cookies de personaliza\u00e7\u00e3o ou funcionais<\/strong><\/p>\n<p>Estes s\u00e3o os cookies respons\u00e1veis por compilar as prioridades da experi\u00eancia do usu\u00e1rio no website, especificando e personalizando algumas das suas caracter\u00edsticas, como, por exemplo, a escolha do idioma, o tipo de navegador a utilizar, etc.<\/p>\n<p><strong>&#8211; Cookies de medi\u00e7\u00e3o ou desempenho<\/strong><\/p>\n<p>Tamb\u00e9m conhecidos como <strong>cookies de an\u00e1lise ou anal\u00edticos,<\/strong> s\u00e3o usados para fazer um seguimento e uma an\u00e1lise do comportamento do usu\u00e1rio na p\u00e1gina conforme este navega no site.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33842 size-full\" title=\"Qual \u00e9 o motivo da preocupa\u00e7\u00e3o com os cookies?\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/02\/analitica-web.png\" alt=\"Qual \u00e9 o motivo da preocupa\u00e7\u00e3o com os cookies?\" width=\"630\" height=\"340\" srcset=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/02\/analitica-web.png 630w, https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/02\/analitica-web-300x162.png 300w, https:\/\/mailrelay.com\/wp-content\/uploads\/2017\/02\/analitica-web-110x59.png 110w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<h2>Qual \u00e9 o motivo da preocupa\u00e7\u00e3o com os cookies?<\/h2>\n<p><strong>O motivo primordial<\/strong> pelo qual os cookies, principalmente, os cookies de terceiros est\u00e3o se tornando um tema de grande preocupa\u00e7\u00e3o e inc\u00f4modo para os usu\u00e1rios \u00e9 o fato de muitos os considerarem como <strong>la invas\u00e3o excessiva da sua privacidade.<\/strong><\/p>\n<p>Nos \u00faltimos anos, todos n\u00f3s usu\u00e1rios sentimos como os an\u00fancios nos perseguem e nos invadem para nos encorajar a comprar determinados produtos a ponto de nos cansarmos e nunca mais querermos aceitar aqueles cookies invasivos e irritantes.<\/p>\n<p>Por este motivo, <strong>Google come\u00e7ou uma iniciativa para deixar de usar as chamadas \u201cPrivacy Sandbox\u201d<\/strong> o que significa que os cookies de terceiros ser\u00e3o exclu\u00eddos para tentar melhorar a prote\u00e7\u00e3o da privacidade do usu\u00e1rio, bem como encontrar novas formas de gegerenciar a publicidade para que seja direcionada espec\u00edficamente ao usu\u00e1rio que desejar receb\u00ea-la.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-32898 size-full\" title=\"por um futuro sem cookies\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/Un-futuro-sin-cookies.png\" alt=\"por um futuro sem cookies\" width=\"320\" height=\"180\" \/><\/p>\n<h3>Por que os cookies ser\u00e3o deixados de usar?<\/h3>\n<p>Como mencionamos anteriormente, a cada dia h\u00e1 uma maior preocupa\u00e7\u00e3o dos usu\u00e1rios em cuidar de sua privacidade, portanto, eliminando cookies de terceiros, ser\u00e1 garantida maior seguran\u00e7a e prote\u00e7\u00e3o dos dados dos usu\u00e1rios, fazendo com que se sintam mais confort\u00e1veis ao navegar na web.<\/p>\n<p>Desta forma, tamb\u00e9m ser\u00e1 eliminada a possibilidade ou risco de as empresas venderem as informa\u00e7\u00f5es que obt\u00eam dos usu\u00e1rios a outras entidades sem o seu consentimento.<\/p>\n<p><strong> Por esses motivos, o Google e outros buscadores se comprometeram a eliminar cookies de terceiros para criar um sistema em que o mais importante seja cuidar da privacidade do usu\u00e1rio, transformando a forma atual de publicidade no mundo do Marketing Digital.<\/strong><\/p>\n<h2>Quais s\u00e3o as alternativas aos cookies?<\/h2>\n<p>Depois de j\u00e1 termos falado sobre o que s\u00e3o os <strong>cookies<\/strong>, os tipos que existem e as raz\u00f5es para a sua elimina\u00e7\u00e3o, agora vem a pr\u00f3xima quest\u00e3o, quais s\u00e3o as op\u00e7\u00f5es alternativas para a evolu\u00e7\u00e3o de um Marketing Digital sem cookies?<\/p>\n<p>As propostas com as quais o Google Chrome assumiu como alternativas para um futuro em que n\u00e3o existam cookies com o seguinte:<\/p>\n<p><strong>&#8211; Privacy Sandbox<\/strong><\/p>\n<p>Como mencionamos anteriormente, o <strong>Privacy Sandbox<\/strong>\u00e9 uma iniciativa que re\u00fane um conjunto de par\u00e2metros para a web a fim de garantir ao usu\u00e1rio o devido cuidado com sua privacidade.<\/p>\n<p><strong>&#8211; Federated Learning of Cohorts<\/strong><\/p>\n<p><strong>O algoritmo FLoC<\/strong> \u00e9 um tipo de tecnologia que une ou segmenta os usu\u00e1rios em v\u00e1rios grupos, melhor conhecidos como <strong>Coortes, em que partilham os mesmos gostos e h\u00e1bitos de navega\u00e7\u00e3o<\/strong>e, desta forma, gerem corretamente e direcionam an\u00fancios (n\u00e3o invasivos) para o p\u00fablico-alvo espec\u00edfico.<\/p>\n<p><strong>&#8211; Uso de dados pr\u00f3prios<\/strong><\/p>\n<p>No campo do Marketing Digital, o fortalecimento do uso de dados pr\u00f3prios permite estabelecer rela\u00e7\u00f5es mais pr\u00f3ximas com os usu\u00e1rios, o que por sua vez tamb\u00e9m aumenta a confian\u00e7a dos usu\u00e1rios e os torna fi\u00e9is \u00e0 marca.<\/p>\n<p>Al\u00e9m disso, fazer uso de dados pr\u00f3prios permite que o <strong>Customer Journey<\/strong>seja mais atrativa e interessante, ou seja, torna o processo de compra do cliente mais pessoal, \u00fanico e divertido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-32900 size-full\" title=\"marketing digital sem cookies\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/Marketing-Digital-sin-cookies.png\" alt=\"marketing digital sem cookies\" width=\"320\" height=\"180\" \/><\/p>\n<h2>Como as empresas se comportar\u00e3o no Marketing Digital sem cookies?<\/h2>\n<p>Promover a privacidade do usu\u00e1rio \u00e9 um desafio para as empresas do mundo do Marketing Digital, tanto para divulgar quanto para realizar estrat\u00e9gias de posicionamento como <strong>SEO ou SEM<\/strong>.<\/p>\n<p>A estrat\u00e9gia de posicionamento SEO consiste em direcionar os usu\u00e1rios de forma natural e org\u00e2nica, utilizando ferramentas como o <strong>Google Analytics <\/strong>para identificar palavras-chave e ver o posicionamento da empresa, assim eliminando cookies de terceiros essa estrat\u00e9gia poderia ser prejudicada.<\/p>\n<p>O desafio num futuro onde n\u00e3o existam <strong>cookies <\/strong>est\u00e1 focado em encontrar uma maneira de rastrear de forma eficaz os dados e informa\u00e7\u00f5es dos usu\u00e1rios, pelo que os efeitos que isso ter\u00e1 no Marketing Digital s\u00e3o como:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Encontrar alternativas para lan\u00e7ar campanhas e an\u00fancios de retargeting e como medi-los. A utiliza\u00e7\u00e3o de dados pr\u00f3prios, sobre os quais j\u00e1 falamos na se\u00e7\u00e3o anterior, seria uma boa op\u00e7\u00e3o.<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Para realizar campanhas pagas, as empresas devem utilizar cookies pr\u00f3prios.<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Os cookies pr\u00f3pios tamb\u00e9m desempenhar\u00e3o um papel importante na cria\u00e7\u00e3o de an\u00fancios relevantes para seu p\u00fablico-alvo.<\/p>\n<p>Para al\u00e9m dos desafios que um <strong>futuro sem cookies <\/strong>representa para as empresas, esta evolu\u00e7\u00e3o ou mudan\u00e7a tamb\u00e9m as faz adaptar-se ao novo normal, pelo que as diretrizes que v\u00e3o nortear o seu comportamento incidir\u00e3o em:<\/p>\n<h3>&#8211; Obter dados que v\u00eam diretamente dos usu\u00e1rios<\/h3>\n<p>Algumas formas <strong>eficazes <\/strong>de obter esses dados s\u00e3o por meio de pesquisas e formul\u00e1rios, seja para obter informa\u00e7\u00f5es gerais ou para conhecer o n\u00edvel de satisfa\u00e7\u00e3o do usu\u00e1rio. Isso garante a privacidade dos usu\u00e1rios e cria uma rela\u00e7\u00e3o mais pr\u00f3xima com eles.<\/p>\n<h3>&#8211; Incentivar convers\u00f5es de usu\u00e1rios<\/h3>\n<p>A otimiza\u00e7\u00e3o de convers\u00e3o (CRO) \u00e9 uma estrat\u00e9gia de Marketing Digital muito \u00fatil para aumentar os lucros gerados no site e, portanto, \u00e9 uma estrat\u00e9gia que tamb\u00e9m \u00e9 prejudicada pelos cookies, por isso as empresas devem implementar estrat\u00e9gias de SEO melhorar a <strong>experi\u00eancia do usu\u00e1rio <\/strong>e obter informa\u00e7\u00f5es deles sem precisar recorrer a eles.<\/p>\n<h3>&#8211; Alcan\u00e7ar a m\u00e1xima transpar\u00eancia<\/h3>\n<p>Dar prioridade para a <strong>privacidade do usu\u00e1rio <\/strong>tamb\u00e9m significa que as empresas devem mostrar-se tais como s\u00e3o e devem informar os usu\u00e1rios o tempo todo sobre como gerenciam as informa\u00e7\u00f5es que est\u00e3o usando e por que o fazem.<\/p>\n<p>Com isso, adquire-se maior confian\u00e7a por parte dos usu\u00e1rios e demonstra-se uma atitude limpa e sincera por parte da empresa.<\/p>\n<h3>&#8211; Definir uma nova pol\u00edtica de privacidade<\/h3>\n<p>Estabelecer <strong>uma pol\u00edtica de privacidade<\/strong> \u00c9 essencial e obrigat\u00f3rio para o novo plano de Marketing Digital sem cookies, pelo que deve caracterizar-se por ser acess\u00edvel ao usu\u00e1rio, de f\u00e1cil compreens\u00e3o e, al\u00e9m disso, deve fornecer as informa\u00e7\u00f5es necess\u00e1rias sobre a utiliza\u00e7\u00e3o e finalidade da obten\u00e7\u00e3o dos cookies.<\/p>\n<h2>Conclus\u00e3o<\/h2>\n<p><strong>A evolu\u00e7\u00e3o para um Marketing Digital sem cookies<\/strong> \u00c9 um fato e um futuro a que todas as empresas do mundo digital ter\u00e3o de se adaptar mais cedo ou mais tarde, pelo que pensar em estrat\u00e9gias e procurar alternativas a seguir \u00e9 essencial para o seu sucesso.<\/p>\n<p>Em suma, estamos entrando em um mundo em que a privacidade do usu\u00e1rio \u00e9 priorizada, o que representa uma grande mudan\u00e7a para a Internet e para as empresas, que devem come\u00e7ar a implementar e tomar medidas nesse sentido.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/camila-restrepo-ortiz-mktdigital\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-32906 size-full\" title=\"Camila Restrepo Ortiz- Traduzido por Micheli\" src=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/camila-restrepo.png\" alt=\"Camila Restrepo Ortiz\" width=\"630\" height=\"250\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos \u00faltimos anos, as empresas tiraram muitas vantagens das informa\u00e7\u00f5es proporcionadas pelos usu\u00e1rios atrav\u00e9s dos cookies, que foram criados em 1994 e foram uma ferramenta fundamental para criar an\u00fancios e lan\u00e7ar campanhas publicit\u00e1rias. Portanto, avan\u00e7ar para o Marketing Digital sem cookies \u00e9 motivo de grande preocupa\u00e7\u00e3o para muitos deles. E n\u00e3o s\u00f3 as empresas ser\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[580,2,16],"tags":[],"class_list":["post-49653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-pt","category-sin-categorizar","category-uncategorized-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como ser\u00e1 o marketing digital sem cookies? - Mailrelay<\/title>\n<meta name=\"description\" content=\"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como ser\u00e1 o marketing digital sem cookies? - Mailrelay\" \/>\n<meta property=\"og:description\" content=\"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailrelay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mailrelay\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-13T20:40:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T10:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mailrelay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:site\" content=\"@mailrelay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mailrelay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/\"},\"author\":{\"name\":\"Mailrelay\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\"},\"headline\":\"Como ser\u00e1 o marketing digital sem cookies?\",\"datePublished\":\"2022-05-13T20:40:24+00:00\",\"dateModified\":\"2022-12-28T10:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/\"},\"wordCount\":2201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png\",\"articleSection\":[\"marketing\",\"Sin categorizar\",\"Uncategorized @pt\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/\",\"name\":\"Como ser\u00e1 o marketing digital sem cookies? - Mailrelay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png\",\"datePublished\":\"2022-05-13T20:40:24+00:00\",\"dateModified\":\"2022-12-28T10:52:31+00:00\",\"description\":\"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png\",\"width\":630,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/2022\\\/05\\\/13\\\/como-sera-o-marketing-digital-sem-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como ser\u00e1 o marketing digital sem cookies?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"name\":\"Mailrelay\",\"description\":\"Mailrelay.com - Email Marketing Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#organization\",\"name\":\"Mailrelay\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mailrelay.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mailrelay-logo.jpg\",\"width\":613,\"height\":291,\"caption\":\"Mailrelay\"},\"image\":{\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mailrelay\\\/\",\"https:\\\/\\\/x.com\\\/mailrelay\",\"https:\\\/\\\/www.youtube.com\\\/mailrelay-email-marketing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/#\\\/schema\\\/person\\\/355071c9f6e00fa8c8731ac93e0aa487\",\"name\":\"Mailrelay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g\",\"caption\":\"Mailrelay\"},\"url\":\"https:\\\/\\\/mailrelay.com\\\/pt\\\/blog\\\/author\\\/mailrelay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como ser\u00e1 o marketing digital sem cookies? - Mailrelay","description":"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/","og_locale":"pt_BR","og_type":"article","og_title":"Como ser\u00e1 o marketing digital sem cookies? - Mailrelay","og_description":"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.","og_url":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/","og_site_name":"Mailrelay","article_publisher":"https:\/\/www.facebook.com\/Mailrelay\/","article_published_time":"2022-05-13T20:40:24+00:00","article_modified_time":"2022-12-28T10:52:31+00:00","og_image":[{"width":630,"height":340,"url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png","type":"image\/png"}],"author":"Mailrelay","twitter_card":"summary_large_image","twitter_creator":"@mailrelay","twitter_site":"@mailrelay","twitter_misc":{"Escrito por":"Mailrelay","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#article","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/"},"author":{"name":"Mailrelay","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487"},"headline":"Como ser\u00e1 o marketing digital sem cookies?","datePublished":"2022-05-13T20:40:24+00:00","dateModified":"2022-12-28T10:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/"},"wordCount":2201,"commentCount":0,"publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png","articleSection":["marketing","Sin categorizar","Uncategorized @pt"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/","url":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/","name":"Como ser\u00e1 o marketing digital sem cookies? - Mailrelay","isPartOf":{"@id":"https:\/\/mailrelay.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#primaryimage"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#primaryimage"},"thumbnailUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png","datePublished":"2022-05-13T20:40:24+00:00","dateModified":"2022-12-28T10:52:31+00:00","description":"Um cookie \u00e9 um arquivo de texto que uma p\u00e1gina web manda ao navegador do seu computador ou dispositivo m\u00f3vel quando voc\u00ea acessa a p\u00e1gina, ou seja, \u00e9 um arquivo de dados que serve para armazenar grandes quantidades de informa\u00e7\u00f5es importantes.","breadcrumb":{"@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#primaryimage","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png","width":630,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/mailrelay.com\/pt\/blog\/2022\/05\/13\/como-sera-o-marketing-digital-sem-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mailrelay.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Como ser\u00e1 o marketing digital sem cookies?"}]},{"@type":"WebSite","@id":"https:\/\/mailrelay.com\/pt\/#website","url":"https:\/\/mailrelay.com\/pt\/","name":"Mailrelay","description":"Mailrelay.com - Email Marketing Software","publisher":{"@id":"https:\/\/mailrelay.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mailrelay.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mailrelay.com\/pt\/#organization","name":"Mailrelay","url":"https:\/\/mailrelay.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","contentUrl":"https:\/\/mailrelay.com\/wp-content\/uploads\/2019\/05\/mailrelay-logo.jpg","width":613,"height":291,"caption":"Mailrelay"},"image":{"@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mailrelay\/","https:\/\/x.com\/mailrelay","https:\/\/www.youtube.com\/mailrelay-email-marketing"]},{"@type":"Person","@id":"https:\/\/mailrelay.com\/pt\/#\/schema\/person\/355071c9f6e00fa8c8731ac93e0aa487","name":"Mailrelay","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/871548d8ea792b1be4dca815f1997730a5a337670dbe077351e8e02f813d2b58?s=96&d=mm&r=g","caption":"Mailrelay"},"url":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",630,340,false],"thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies-150x150.png",150,150,true],"medium":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies-300x162.png",300,162,true],"medium_large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",630,340,false],"large":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",630,340,false],"1536x1536":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",630,340,false],"2048x2048":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",630,340,false],"testimonials":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies-110x59.png",110,59,true],"author-image":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies-60x32.png",60,32,true],"yarpp-thumbnail":["https:\/\/mailrelay.com\/wp-content\/uploads\/2022\/05\/\u00bfComo-sera-el-Marketing-Digital-sin-cookies.png",120,65,false]},"uagb_author_info":{"display_name":"Mailrelay","author_link":"https:\/\/mailrelay.com\/pt\/blog\/author\/mailrelay\/"},"uagb_comment_info":2,"uagb_excerpt":"Nos \u00faltimos anos, as empresas tiraram muitas vantagens das informa\u00e7\u00f5es proporcionadas pelos usu\u00e1rios atrav\u00e9s dos cookies, que foram criados em 1994 e foram uma ferramenta fundamental para criar an\u00fancios e lan\u00e7ar campanhas publicit\u00e1rias. Portanto, avan\u00e7ar para o Marketing Digital sem cookies \u00e9 motivo de grande preocupa\u00e7\u00e3o para muitos deles. E n\u00e3o s\u00f3 as empresas ser\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/49653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/comments?post=49653"}],"version-history":[{"count":3,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/49653\/revisions"}],"predecessor-version":[{"id":59510,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/posts\/49653\/revisions\/59510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media\/47722"}],"wp:attachment":[{"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/media?parent=49653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/categories?post=49653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mailrelay.com\/pt\/wp-json\/wp\/v2\/tags?post=49653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}